{"id":597,"count":1,"description":"","link":"https:\/\/www.modernwildlifecontrol.com\/blog\/category\/animal-damage-repair\/","name":"Animal Damage Repair","slug":"animal-damage-repair","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/www.modernwildlifecontrol.com\/blog\/wp-json\/wp\/v2\/categories\/597","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.modernwildlifecontrol.com\/blog\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/www.modernwildlifecontrol.com\/blog\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/www.modernwildlifecontrol.com\/blog\/wp-json\/wp\/v2\/posts?categories=597"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}